{"id":14749,"count":0,"description":"","link":"https:\/\/dutchmuseumgiftshop.nl\/nl\/product-brand\/yin-yoga-cards-nl\/","name":"Yin Yoga Cards","slug":"yin-yoga-cards-nl","taxonomy":"product_brand","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Yin Yoga Cards - Dutch Museum Gift Shop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dutchmuseumgiftshop.nl\/nl\/product-brand\/yin-yoga-cards-nl\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yin Yoga Cards\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dutchmuseumgiftshop.nl\/nl\/product-brand\/yin-yoga-cards-nl\/\" \/>\n<meta property=\"og:site_name\" content=\"Dutch Museum Gift Shop\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2020\/01\/cropped-logo-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"553\" \/>\n\t<meta property=\"og:image:height\" content=\"325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@museumgifts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/nl\\\/product-brand\\\/yin-yoga-cards-nl\\\/\",\"url\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/nl\\\/product-brand\\\/yin-yoga-cards-nl\\\/\",\"name\":\"Yin Yoga Cards - Dutch Museum Gift Shop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/nl\\\/product-brand\\\/yin-yoga-cards-nl\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/nl\\\/product-brand\\\/yin-yoga-cards-nl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yin Yoga Cards\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/nl\\\/\",\"name\":\"Dutch Museum Gift Shop\",\"description\":\"The best gifts from Dutch museums\",\"publisher\":{\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/nl\\\/#organization\"},\"alternateName\":\"DMGS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/nl\\\/#organization\",\"name\":\"Dutch Museum Gift Shop\",\"alternateName\":\"DMGS\",\"url\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cropped-logo-1-1.png\",\"contentUrl\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cropped-logo-1-1.png\",\"width\":553,\"height\":325,\"caption\":\"Dutch Museum Gift Shop\"},\"image\":{\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dutchmuseumgiftshop\\\/\",\"https:\\\/\\\/x.com\\\/museumgifts\",\"https:\\\/\\\/www.instagram.com\\\/dutchmuseumgiftshop\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dutchmuseumgiftshop\\\/\",\"https:\\\/\\\/nl.pinterest.com\\\/museumgifts\\\/\"],\"description\":\"DMGS aims to promote and sell products from museums in order to support cultural heritage and to give museums an independent source of income.\",\"email\":\"info@dutchmuseumgiftshop.nl\",\"legalName\":\"Dutch Museum Gift Shop B.V.\",\"foundingDate\":\"2020-05-04\",\"vatID\":\"NL865271690B01\",\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/client-services\\\/return-policy\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Yin Yoga Cards - Dutch Museum Gift Shop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dutchmuseumgiftshop.nl\/nl\/product-brand\/yin-yoga-cards-nl\/","og_locale":"nl_NL","og_type":"article","og_title":"Yin Yoga Cards","og_url":"https:\/\/dutchmuseumgiftshop.nl\/nl\/product-brand\/yin-yoga-cards-nl\/","og_site_name":"Dutch Museum Gift Shop","og_image":[{"width":553,"height":325,"url":"https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2020\/01\/cropped-logo-1-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@museumgifts","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/dutchmuseumgiftshop.nl\/nl\/product-brand\/yin-yoga-cards-nl\/","url":"https:\/\/dutchmuseumgiftshop.nl\/nl\/product-brand\/yin-yoga-cards-nl\/","name":"Yin Yoga Cards - Dutch Museum Gift Shop","isPartOf":{"@id":"https:\/\/dutchmuseumgiftshop.nl\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/dutchmuseumgiftshop.nl\/nl\/product-brand\/yin-yoga-cards-nl\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/dutchmuseumgiftshop.nl\/nl\/product-brand\/yin-yoga-cards-nl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dutchmuseumgiftshop.nl\/nl\/"},{"@type":"ListItem","position":2,"name":"Yin Yoga Cards"}]},{"@type":"WebSite","@id":"https:\/\/dutchmuseumgiftshop.nl\/nl\/#website","url":"https:\/\/dutchmuseumgiftshop.nl\/nl\/","name":"Dutch Museum Gift Shop","description":"The best gifts from Dutch museums","publisher":{"@id":"https:\/\/dutchmuseumgiftshop.nl\/nl\/#organization"},"alternateName":"DMGS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dutchmuseumgiftshop.nl\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/dutchmuseumgiftshop.nl\/nl\/#organization","name":"Dutch Museum Gift Shop","alternateName":"DMGS","url":"https:\/\/dutchmuseumgiftshop.nl\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/dutchmuseumgiftshop.nl\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2020\/01\/cropped-logo-1-1.png","contentUrl":"https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2020\/01\/cropped-logo-1-1.png","width":553,"height":325,"caption":"Dutch Museum Gift Shop"},"image":{"@id":"https:\/\/dutchmuseumgiftshop.nl\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dutchmuseumgiftshop\/","https:\/\/x.com\/museumgifts","https:\/\/www.instagram.com\/dutchmuseumgiftshop","https:\/\/www.linkedin.com\/company\/dutchmuseumgiftshop\/","https:\/\/nl.pinterest.com\/museumgifts\/"],"description":"DMGS aims to promote and sell products from museums in order to support cultural heritage and to give museums an independent source of income.","email":"info@dutchmuseumgiftshop.nl","legalName":"Dutch Museum Gift Shop B.V.","foundingDate":"2020-05-04","vatID":"NL865271690B01","hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/dutchmuseumgiftshop.nl\/client-services\/return-policy\/"}}]}},"_links":{"self":[{"href":"https:\/\/dutchmuseumgiftshop.nl\/nl\/wp-json\/wp\/v2\/product_brand\/14749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dutchmuseumgiftshop.nl\/nl\/wp-json\/wp\/v2\/product_brand"}],"about":[{"href":"https:\/\/dutchmuseumgiftshop.nl\/nl\/wp-json\/wp\/v2\/taxonomies\/product_brand"}],"wp:post_type":[{"href":"https:\/\/dutchmuseumgiftshop.nl\/nl\/wp-json\/wp\/v2\/product?product_brand=14749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}