{"id":14418,"count":24,"description":"Piet Design a \u00e9t\u00e9 fond\u00e9e en 1990 par Elisabeth (Piet) Rijkels-Visser (1972). L'agence de design est sp\u00e9cialis\u00e9e dans les produits \u00e0 monter soi-m\u00eame, respectueux de l'histoire, qui sont vendus dans les boutiques de mus\u00e9es en Allemagne et \u00e0 l'\u00e9tranger.","link":"https:\/\/dutchmuseumgiftshop.nl\/fr\/product-brand\/piet-design-fr\/","name":"Piet Design","slug":"piet-design-fr","taxonomy":"product_brand","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Piet Design - Dutch Museum Gift Shop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dutchmuseumgiftshop.nl\/fr\/product-brand\/piet-design-fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piet Design\" \/>\n<meta property=\"og:description\" content=\"Piet Design a \u00e9t\u00e9 fond\u00e9e en 1990 par Elisabeth (Piet) Rijkels-Visser (1972). L&rsquo;agence de design est sp\u00e9cialis\u00e9e dans les produits \u00e0 monter soi-m\u00eame, respectueux de l&rsquo;histoire, qui sont vendus dans les boutiques de mus\u00e9es en Allemagne et \u00e0 l&rsquo;\u00e9tranger.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dutchmuseumgiftshop.nl\/fr\/product-brand\/piet-design-fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Dutch Museum Gift Shop\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2020\/01\/cropped-logo-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"553\" \/>\n\t<meta property=\"og:image:height\" content=\"325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@museumgifts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/product-brand\\\/piet-design-fr\\\/\",\"url\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/product-brand\\\/piet-design-fr\\\/\",\"name\":\"Piet Design - Dutch Museum Gift Shop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/product-brand\\\/piet-design-fr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/product-brand\\\/piet-design-fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piet Design\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/\",\"name\":\"Dutch Museum Gift Shop\",\"description\":\"The best gifts from Dutch museums\",\"publisher\":{\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/#organization\"},\"alternateName\":\"DMGS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/#organization\",\"name\":\"Dutch Museum Gift Shop\",\"alternateName\":\"DMGS\",\"url\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cropped-logo-1-1.png\",\"contentUrl\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cropped-logo-1-1.png\",\"width\":553,\"height\":325,\"caption\":\"Dutch Museum Gift Shop\"},\"image\":{\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dutchmuseumgiftshop\\\/\",\"https:\\\/\\\/x.com\\\/museumgifts\",\"https:\\\/\\\/www.instagram.com\\\/dutchmuseumgiftshop\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dutchmuseumgiftshop\\\/\",\"https:\\\/\\\/nl.pinterest.com\\\/museumgifts\\\/\"],\"description\":\"DMGS aims to promote and sell products from museums in order to support cultural heritage and to give museums an independent source of income.\",\"email\":\"info@dutchmuseumgiftshop.nl\",\"legalName\":\"Dutch Museum Gift Shop B.V.\",\"foundingDate\":\"2020-05-04\",\"vatID\":\"NL865271690B01\",\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/client-services\\\/return-policy\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Piet Design - Dutch Museum Gift Shop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dutchmuseumgiftshop.nl\/fr\/product-brand\/piet-design-fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Piet Design","og_description":"Piet Design a \u00e9t\u00e9 fond\u00e9e en 1990 par Elisabeth (Piet) Rijkels-Visser (1972). L&rsquo;agence de design est sp\u00e9cialis\u00e9e dans les produits \u00e0 monter soi-m\u00eame, respectueux de l&rsquo;histoire, qui sont vendus dans les boutiques de mus\u00e9es en Allemagne et \u00e0 l&rsquo;\u00e9tranger.","og_url":"https:\/\/dutchmuseumgiftshop.nl\/fr\/product-brand\/piet-design-fr\/","og_site_name":"Dutch Museum Gift Shop","og_image":[{"width":553,"height":325,"url":"https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2020\/01\/cropped-logo-1-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@museumgifts","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/product-brand\/piet-design-fr\/","url":"https:\/\/dutchmuseumgiftshop.nl\/fr\/product-brand\/piet-design-fr\/","name":"Piet Design - Dutch Museum Gift Shop","isPartOf":{"@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/product-brand\/piet-design-fr\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/product-brand\/piet-design-fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dutchmuseumgiftshop.nl\/fr\/"},{"@type":"ListItem","position":2,"name":"Piet Design"}]},{"@type":"WebSite","@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/#website","url":"https:\/\/dutchmuseumgiftshop.nl\/fr\/","name":"Dutch Museum Gift Shop","description":"The best gifts from Dutch museums","publisher":{"@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/#organization"},"alternateName":"DMGS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dutchmuseumgiftshop.nl\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/#organization","name":"Dutch Museum Gift Shop","alternateName":"DMGS","url":"https:\/\/dutchmuseumgiftshop.nl\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2020\/01\/cropped-logo-1-1.png","contentUrl":"https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2020\/01\/cropped-logo-1-1.png","width":553,"height":325,"caption":"Dutch Museum Gift Shop"},"image":{"@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dutchmuseumgiftshop\/","https:\/\/x.com\/museumgifts","https:\/\/www.instagram.com\/dutchmuseumgiftshop","https:\/\/www.linkedin.com\/company\/dutchmuseumgiftshop\/","https:\/\/nl.pinterest.com\/museumgifts\/"],"description":"DMGS aims to promote and sell products from museums in order to support cultural heritage and to give museums an independent source of income.","email":"info@dutchmuseumgiftshop.nl","legalName":"Dutch Museum Gift Shop B.V.","foundingDate":"2020-05-04","vatID":"NL865271690B01","hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/dutchmuseumgiftshop.nl\/client-services\/return-policy\/"}}]}},"_links":{"self":[{"href":"https:\/\/dutchmuseumgiftshop.nl\/fr\/wp-json\/wp\/v2\/product_brand\/14418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dutchmuseumgiftshop.nl\/fr\/wp-json\/wp\/v2\/product_brand"}],"about":[{"href":"https:\/\/dutchmuseumgiftshop.nl\/fr\/wp-json\/wp\/v2\/taxonomies\/product_brand"}],"wp:post_type":[{"href":"https:\/\/dutchmuseumgiftshop.nl\/fr\/wp-json\/wp\/v2\/product?product_brand=14418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}