{"id":128216,"date":"2024-11-17T21:10:11","date_gmt":"2024-11-17T20:10:11","guid":{"rendered":"https:\/\/dutchmuseumgiftshop.nl\/store\/dmgselect\/product\/masque-de-sommeil-autoportrait-de-rembrandt\/"},"modified":"2024-12-17T21:10:11","modified_gmt":"2024-12-17T20:10:11","slug":"masque-de-sommeil-autoportrait-de-rembrandt","status":"publish","type":"product","link":"https:\/\/dutchmuseumgiftshop.nl\/fr\/store\/dmgselect\/product\/masque-de-sommeil-autoportrait-de-rembrandt\/","title":{"rendered":"Masque de sommeil | Autoportrait de Rembrandt"},"content":{"rendered":"<ul>\n<li>Dimensions du masque pour les yeux : 200 x 110 x 10 mm<\/li>\n<li>Mati\u00e8re : 100 % polyester<\/li>\n<li>Bande \u00e9lastique r\u00e9glable<\/li>\n<li>Lavage en machine \u00e0 chaud, repassage \u00e0 temp\u00e9rature moyenne, s\u00e9chage au s\u00e8che-linge \u00e0 basse temp\u00e9rature<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Endormez-vous avec style gr\u00e2ce \u00e0 ce masque de sommeil unique repr\u00e9sentant l&#8217;embl\u00e9matique <em>Autoportrait <\/em>de Rembrandt. Alliant confort et art, il est parfait pour les voyages, les siestes ou une nuit de sommeil r\u00e9paratrice. Un incontournable pour les amateurs d&rsquo;art qui veulent r\u00eaver comme un ma\u00eetre.  <\/p>\n","protected":false},"featured_media":128156,"comment_status":"open","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[14500],"product_cat":[8694,8711],"product_tag":[8447,9131],"class_list":["post-128216","product","type-product","status-publish","has-post-thumbnail","product_brand-lanzfeld-fr","product_cat-accessoires-fr","product_cat-cadeaux-sympas","product_tag-fete-des-peres","product_tag-rembrandt-fr","product_shipping_class-nedline-fr","pa_artist-rembrandt-van-rijn-fr","pa_brand-lanzfeld","pa_material-100-polyester-fr","desktop-align-left","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal","ast-product-tabs-layout-horizontal","first","instock","taxable","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Masque de sommeil | Autoportrait de Rembrandt - Dutch Museum Gift Shop - Dutch Museum Gift Shop<\/title>\n<meta name=\"description\" content=\"Vivez une d\u00e9tente absolue avec notre masque de sommeil autoportrait de Rembrandt. Bandeau r\u00e9glable, rembourrage doux et design occultant pour un sommeil profond et ininterrompu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dutchmuseumgiftshop.nl\/fr\/store\/dmgselect\/product\/masque-de-sommeil-autoportrait-de-rembrandt\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Masque de sommeil | Autoportrait de Rembrandt\" \/>\n<meta property=\"og:description\" content=\"Vivez une d\u00e9tente absolue avec notre masque de sommeil autoportrait de Rembrandt. Bandeau r\u00e9glable, rembourrage doux et design occultant pour un sommeil profond et ininterrompu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dutchmuseumgiftshop.nl\/fr\/store\/dmgselect\/product\/masque-de-sommeil-autoportrait-de-rembrandt\/\" \/>\n<meta property=\"og:site_name\" content=\"Dutch Museum Gift Shop\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dutchmuseumgiftshop\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-17T20:10:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@museumgifts\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;12,75\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/store\\\/dmgselect\\\/product\\\/masque-de-sommeil-autoportrait-de-rembrandt\\\/\",\"url\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/store\\\/dmgselect\\\/product\\\/masque-de-sommeil-autoportrait-de-rembrandt\\\/\",\"name\":\"Masque de sommeil | Autoportrait de Rembrandt - Dutch Museum Gift Shop - Dutch Museum Gift Shop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/store\\\/dmgselect\\\/product\\\/masque-de-sommeil-autoportrait-de-rembrandt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/store\\\/dmgselect\\\/product\\\/masque-de-sommeil-autoportrait-de-rembrandt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/slaapmasker-rembrandt-zelfportret1.jpg\",\"datePublished\":\"2024-11-17T20:10:11+00:00\",\"dateModified\":\"2024-12-17T20:10:11+00:00\",\"description\":\"Vivez une d\u00e9tente absolue avec notre masque de sommeil autoportrait de Rembrandt. Bandeau r\u00e9glable, rembourrage doux et design occultant pour un sommeil profond et ininterrompu.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/store\\\/dmgselect\\\/product\\\/masque-de-sommeil-autoportrait-de-rembrandt\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/store\\\/dmgselect\\\/product\\\/masque-de-sommeil-autoportrait-de-rembrandt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/store\\\/dmgselect\\\/product\\\/masque-de-sommeil-autoportrait-de-rembrandt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/slaapmasker-rembrandt-zelfportret1.jpg\",\"contentUrl\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/slaapmasker-rembrandt-zelfportret1.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Masque de sommeil | Autoportrait de Rembrandt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/store\\\/dmgselect\\\/product\\\/masque-de-sommeil-autoportrait-de-rembrandt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Masque de sommeil | Autoportrait de Rembrandt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/\",\"name\":\"Dutch Museum Gift Shop\",\"description\":\"The best gifts from Dutch museums\",\"publisher\":{\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/#organization\"},\"alternateName\":\"DMGS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/#organization\",\"name\":\"Dutch Museum Gift Shop\",\"alternateName\":\"DMGS\",\"url\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cropped-logo-1-1.png\",\"contentUrl\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cropped-logo-1-1.png\",\"width\":553,\"height\":325,\"caption\":\"Dutch Museum Gift Shop\"},\"image\":{\"@id\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dutchmuseumgiftshop\\\/\",\"https:\\\/\\\/x.com\\\/museumgifts\",\"https:\\\/\\\/www.instagram.com\\\/dutchmuseumgiftshop\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dutchmuseumgiftshop\\\/\",\"https:\\\/\\\/nl.pinterest.com\\\/museumgifts\\\/\"],\"description\":\"DMGS aims to promote and sell products from museums in order to support cultural heritage and to give museums an independent source of income.\",\"email\":\"info@dutchmuseumgiftshop.nl\",\"legalName\":\"Dutch Museum Gift Shop B.V.\",\"foundingDate\":\"2020-05-04\",\"vatID\":\"NL865271690B01\",\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/dutchmuseumgiftshop.nl\\\/client-services\\\/return-policy\\\/\"}}]}<\/script>\n<meta property=\"product:brand\" content=\"Lanzfeld\" \/>\n<meta property=\"product:price:amount\" content=\"12.75\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"ASMW000007(EXT)\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Masque de sommeil | Autoportrait de Rembrandt - Dutch Museum Gift Shop - Dutch Museum Gift Shop","description":"Vivez une d\u00e9tente absolue avec notre masque de sommeil autoportrait de Rembrandt. Bandeau r\u00e9glable, rembourrage doux et design occultant pour un sommeil profond et ininterrompu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dutchmuseumgiftshop.nl\/fr\/store\/dmgselect\/product\/masque-de-sommeil-autoportrait-de-rembrandt\/","og_locale":"fr_FR","og_type":"article","og_title":"Masque de sommeil | Autoportrait de Rembrandt","og_description":"Vivez une d\u00e9tente absolue avec notre masque de sommeil autoportrait de Rembrandt. Bandeau r\u00e9glable, rembourrage doux et design occultant pour un sommeil profond et ininterrompu.","og_url":"https:\/\/dutchmuseumgiftshop.nl\/fr\/store\/dmgselect\/product\/masque-de-sommeil-autoportrait-de-rembrandt\/","og_site_name":"Dutch Museum Gift Shop","article_publisher":"https:\/\/www.facebook.com\/dutchmuseumgiftshop\/","article_modified_time":"2024-12-17T20:10:11+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@museumgifts","twitter_misc":{"Prix":"&euro;12,75","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/store\/dmgselect\/product\/masque-de-sommeil-autoportrait-de-rembrandt\/","url":"https:\/\/dutchmuseumgiftshop.nl\/fr\/store\/dmgselect\/product\/masque-de-sommeil-autoportrait-de-rembrandt\/","name":"Masque de sommeil | Autoportrait de Rembrandt - Dutch Museum Gift Shop - Dutch Museum Gift Shop","isPartOf":{"@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/store\/dmgselect\/product\/masque-de-sommeil-autoportrait-de-rembrandt\/#primaryimage"},"image":{"@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/store\/dmgselect\/product\/masque-de-sommeil-autoportrait-de-rembrandt\/#primaryimage"},"thumbnailUrl":"https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1.jpg","datePublished":"2024-11-17T20:10:11+00:00","dateModified":"2024-12-17T20:10:11+00:00","description":"Vivez une d\u00e9tente absolue avec notre masque de sommeil autoportrait de Rembrandt. Bandeau r\u00e9glable, rembourrage doux et design occultant pour un sommeil profond et ininterrompu.","breadcrumb":{"@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/store\/dmgselect\/product\/masque-de-sommeil-autoportrait-de-rembrandt\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dutchmuseumgiftshop.nl\/fr\/store\/dmgselect\/product\/masque-de-sommeil-autoportrait-de-rembrandt\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/store\/dmgselect\/product\/masque-de-sommeil-autoportrait-de-rembrandt\/#primaryimage","url":"https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1.jpg","contentUrl":"https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1.jpg","width":1000,"height":1000,"caption":"Masque de sommeil | Autoportrait de Rembrandt"},{"@type":"BreadcrumbList","@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/store\/dmgselect\/product\/masque-de-sommeil-autoportrait-de-rembrandt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dutchmuseumgiftshop.nl\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/dutchmuseumgiftshop.nl\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Masque de sommeil | Autoportrait de Rembrandt"}]},{"@type":"WebSite","@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/#website","url":"https:\/\/dutchmuseumgiftshop.nl\/fr\/","name":"Dutch Museum Gift Shop","description":"The best gifts from Dutch museums","publisher":{"@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/#organization"},"alternateName":"DMGS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dutchmuseumgiftshop.nl\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/#organization","name":"Dutch Museum Gift Shop","alternateName":"DMGS","url":"https:\/\/dutchmuseumgiftshop.nl\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2020\/01\/cropped-logo-1-1.png","contentUrl":"https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2020\/01\/cropped-logo-1-1.png","width":553,"height":325,"caption":"Dutch Museum Gift Shop"},"image":{"@id":"https:\/\/dutchmuseumgiftshop.nl\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dutchmuseumgiftshop\/","https:\/\/x.com\/museumgifts","https:\/\/www.instagram.com\/dutchmuseumgiftshop","https:\/\/www.linkedin.com\/company\/dutchmuseumgiftshop\/","https:\/\/nl.pinterest.com\/museumgifts\/"],"description":"DMGS aims to promote and sell products from museums in order to support cultural heritage and to give museums an independent source of income.","email":"info@dutchmuseumgiftshop.nl","legalName":"Dutch Museum Gift Shop B.V.","foundingDate":"2020-05-04","vatID":"NL865271690B01","hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/dutchmuseumgiftshop.nl\/client-services\/return-policy\/"}}]},"product_brand":"Lanzfeld","product_price_amount":"12.75","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"ASMW000007(EXT)","product_condition":"new"},"uagb_featured_image_src":{"full":["https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1.jpg",1000,1000,false],"thumbnail":["https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1-280x280.jpg",280,280,true],"medium":["https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1-350x350.jpg",350,350,true],"medium_large":["https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1-768x768.jpg",768,768,true],"large":["https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1.jpg",1000,1000,false],"1536x1536":["https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1.jpg",1000,1000,false],"2048x2048":["https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1.jpg",1000,1000,false],"shareaholic-thumbnail":["https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1-640x640.jpg",640,640,true],"woocommerce_thumbnail":["https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1-350x350.jpg",350,350,true],"woocommerce_gallery_thumbnail":["https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1-280x280.jpg",280,280,true],"shop_catalog":["https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1-280x280.jpg",280,280,true],"woocommerce_single":["https:\/\/dutchmuseumgiftshop.nl\/wp-content\/uploads\/2024\/12\/slaapmasker-rembrandt-zelfportret1-600x600.jpg",600,600,true]},"uagb_author_info":{"display_name":"rijkswebshop","author_link":"https:\/\/dutchmuseumgiftshop.nl\/fr\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Endormez-vous avec style gr\u00e2ce \u00e0 ce masque de sommeil unique repr\u00e9sentant l'embl\u00e9matique Autoportrait de Rembrandt. Alliant confort et art, il est parfait pour les voyages, les siestes ou une nuit de sommeil r\u00e9paratrice. Un incontournable pour les amateurs d'art qui veulent r\u00eaver comme un ma\u00eetre.","_links":{"self":[{"href":"https:\/\/dutchmuseumgiftshop.nl\/fr\/wp-json\/wp\/v2\/product\/128216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dutchmuseumgiftshop.nl\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dutchmuseumgiftshop.nl\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dutchmuseumgiftshop.nl\/fr\/wp-json\/wp\/v2\/comments?post=128216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dutchmuseumgiftshop.nl\/fr\/wp-json\/wp\/v2\/media\/128156"}],"wp:attachment":[{"href":"https:\/\/dutchmuseumgiftshop.nl\/fr\/wp-json\/wp\/v2\/media?parent=128216"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dutchmuseumgiftshop.nl\/fr\/wp-json\/wp\/v2\/product_brand?post=128216"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dutchmuseumgiftshop.nl\/fr\/wp-json\/wp\/v2\/product_cat?post=128216"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dutchmuseumgiftshop.nl\/fr\/wp-json\/wp\/v2\/product_tag?post=128216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}